{"id":168004,"date":"2024-04-09T03:51:48","date_gmt":"2024-04-09T02:51:48","guid":{"rendered":"https:\/\/eu.intelligentlabs.org\/glucosamina-condroitina\/"},"modified":"2025-09-23T11:17:33","modified_gmt":"2025-09-23T10:17:33","slug":"glucosamina-condroitina","status":"publish","type":"post","link":"https:\/\/eu.intelligentlabs.org\/pt-pt\/glucosamina-condroitina\/","title":{"rendered":"Glucosamina Condroitina Suplemento para Articula\u00e7\u00f5es"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A Glucosamina condroitina \u00e9 um dos suplementos mais frequentemente utilizados para as articula\u00e7\u00f5es.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quimicamente, \u00e9 um amino-a\u00e7\u00facar. Este componente tem um papel importante na produ\u00e7\u00e3o e manuten\u00e7\u00e3o da cartilagem. Quando utilizado como um suplemento, o modo preciso da sua ac\u00e7\u00e3o analgesia e salva-guarda da cartilagem ao n\u00edvel molecular n\u00e3o \u00e9 totalmente conhecido. Provavelmente trabalha para diminuir a produ\u00e7\u00e3o de mediadores pr\u00f3-inflamat\u00f3rios que danificam a composi\u00e7\u00e3o da cartilagem (3).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os resultados de suporte em ensaios cl\u00ednicos aleat\u00f3rios, sem d\u00favida, aumentaram a popularidade da glucosamina. Por exemplo, o estudo publicado no prestigiado jornal cient\u00edfico &#8220;Lancet&#8221; em 2001 revelou que a glucosamina tem um impacto na preserva\u00e7\u00e3o da estrutura da articula\u00e7\u00e3o, n\u00e3o apenas nos sintomas de pacientes com osteoartrite&nbsp;(4).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O Que Precisa Saber Sobre Condroitina?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Condroitina \u00e9 um componente org\u00e2nico com um papel essencial na forma\u00e7\u00e3o da cartilagem.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pertence ao grupo de glicosaminoglicanos. Como suplemento sem prescri\u00e7\u00e3o, vem maioritariamente sob a forma de sulfato de condroitina. A suplementa\u00e7\u00e3o de condroitina tem sido utilizada no tratamento de doen\u00e7as degenerativas das articula\u00e7\u00f5es \u00e0 muito tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A suplementa\u00e7\u00e3o de condroitina est\u00e1 associada ao poss\u00edvel impacto na preven\u00e7\u00e3o da degrada\u00e7\u00e3o da cartilagem e a estimula\u00e7\u00e3o de processos de sintetiza\u00e7\u00e3o entre os tecidos cartilaginosos (5). Este suplemento de articula\u00e7\u00f5es tem atividade anti-inflamat\u00f3ria que leva \u00e0 melhoria dos sintomas de osteoartrite (6). Em articula\u00e7\u00f5es osteoartr\u00edticas com mudan\u00e7as radiologicamente verificadas, a condroitina tem o potencial de desacelerar o estreitamento do espa\u00e7o articular. isto \u00e9, para preservar a cartilagem&nbsp;(7).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Glucosamina Condroitina Alivia a Dor da Osteoartrite?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A osteoartrite \u00e9 uma doen\u00e7a altamente prevalente. \u00c9 estimado que cerca de 10% de homens e 18% de mulheres acima dos 60 aos de idade tenham esta doen\u00e7a. A predi\u00e7\u00e3o \u00e9 que estas percentagens seriam ainda mais elevadas&nbsp;(8). O desenvolvimento de mudan\u00e7as estruturais entre as articula\u00e7\u00f5es eventualmente resulta em dor cr\u00f3nica, rigidez de articula\u00e7\u00e3o, mobilidade reduzida e deteriora\u00e7\u00e3o da qualidade de vida. A osteoartrite afeta maioritariamente o joelho, anca e pequenas articula\u00e7\u00f5es da m\u00e3o. Os mais famosos suplementos de articula\u00e7\u00f5es para osteoartrite, glucosammina, e condroitina, t\u00eam o objetivo de prevenir futuras degrada\u00e7\u00f5es da cartilagem e melhorar os sintomas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os resultados dos estudos cient\u00edficos revelam conclus\u00f5es muito diferentes sobre a <strong>efic\u00e1cia da glucosamina e condroitina<\/strong>. Mesmo assim, in\u00fameros estudos suportam a afirma\u00e7\u00e3o de que estes dois suplementos s\u00e3o efetivos no controlo da osteoartrite.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Alguns Estudos Sobre a Efic\u00e1cia da Glucosamina<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Cientistas Japoneses, que publicaram resultados duma revis\u00e3o sistem\u00e1tica e meta-an\u00e1lise no jornal &#8220;Clincal Rheumatology&#8221; em 2018, conclu\u00edram que a glucosamina tem o potencial de aliviar a dor no joelho da osteoartrite (9). Noutra revis\u00e3o sistem\u00e1tica e meta-an\u00e1lise de 2018 tamb\u00e9m anunciou um efeito positivo da glucosamina na redu\u00e7\u00e3o da dor da osteoartrite(10). O papel positivo da condroitina no controlo da dor da osteoartrite \u00e9 tamb\u00e9m confirmado da mesma forma, atrav\u00e9s duma revis\u00e3o sistem\u00e1tica e meta-an\u00e1lise de suplementos para articula\u00e7\u00f5es (11).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O suplemento de articula\u00e7\u00f5es de&nbsp;<strong><a href=\"https:\/\/eu.intelligentlabs.org\/pt-pt\/produto\/glucosamina\/\" target=\"_blank\" rel=\"noreferrer noopener\">Glucosamina da Intelligent Labs<\/a><\/strong>&nbsp;\u00e9 especialmente designado para primeiramente reduzir a inflama\u00e7\u00e3o e depois dar ao corpo a formula exata de glicosaminoglicanos e colag\u00e9nio necess\u00e1rio para reconstruir as articula\u00e7\u00f5es, reduzir a dor, e aumentar a mobilidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qual \u00e9 a Dose Recomendada de Glucosamina Condroitina?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A dose de sulfato de glucosamina utilizada na maioria dos ensaios \u00e9 de <strong>1500 mg<\/strong> por dia. Em alguns pap\u00e9is cient\u00edficos, a dose mencionada acima \u00e9 especificamente designada como a dose recomendada (12).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tem sido observado que tomar doses menores durante o dia para o controlo da dor da osteoartrite (exemplo, 500 mg tr\u00eas vezes ao dia) \u00e9 mais eficaz do que a dose completa de 1500 mg de uma s\u00f3 vez (10).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pelo contr\u00e1rio, a dose de sulfato de condroitina de suplementos de articula\u00e7\u00f5es em v\u00e1rios ensaios varia bastante. A dose entre 800 e 1200 mg por dia tem sido tipicamente recomendada para o tratamento de osteoartrite do joelho (13). No entanto, recentemente, foi reportado que o consumo de sulfato de condroitina (1800 mg\/dia) durante 12 semanas ou mais, tem efeito positivo nas fun\u00e7\u00f5es do joelho e actividades f\u00edsicas de casa em pessoas de meia-idade e adultos mais velhos com dores de joelhos (14).&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ca.intelligentlabs.org\/wp-content\/uploads\/sites\/2\/2020\/03\/glucosamine-chondroitin-joint-supplement-01.jpg\" alt=\"Glucosamina \u00e9 um dos suplementos de artrite mais usados para dor no joelho\" width=\"1200\" height=\"600\">Porqu\u00ea que Sentimos Dor nas Articula\u00e7\u00f5es?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os suplementos de articula\u00e7\u00f5es s\u00e3o as melhores alternativas \u00e0s drogas padr\u00e3o utilizadas para dor de articula\u00e7\u00e3o cr\u00f3nica. As articula\u00e7\u00f5es s\u00e3o propensas a altera\u00e7\u00f5es degenerativas, e milh\u00f5es de pessoas no mundo sofrem com dor cr\u00f3nica na articula\u00e7\u00e3o. Uma vez que o diagn\u00f3stico da doen\u00e7a da articula\u00e7\u00e3o se torne \u00f3bvio, existem m\u00faltiplas estrat\u00e9gias que apresentam o nosso armamento na luta contra a doen\u00e7a da articula\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 na nossa natureza humana que n\u00e3o pensamos muito na nossa sa\u00fade quando os sintomas n\u00e3o est\u00e3o l\u00e1. Estar\u00edamos tolerantes da nossa obesidade ou dieta n\u00e3o saud\u00e1vel at\u00e9 ao momento que os problemas aparecem. A nossa atitude em rela\u00e7\u00e3o as articula\u00e7\u00f5es n\u00e3o \u00e9 excep\u00e7\u00e3o, e tudo est\u00e1 bem enquanto estas funcionam corretamente, Infelizmente, estas estruturas anat\u00f3micas quase perfeitas n\u00e3o s\u00e3o compostas de a\u00e7o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem Consome Suplementos de Articula\u00e7\u00e3o?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O facto de que em torno de 62,5% dos indiv\u00edduos adultos sofre de artrite toma suplementos alimentares de articula\u00e7\u00e3o comparado a 49,00% dos que n\u00e3o t\u00eam artrite \u00e9 bastante indicativo&nbsp;(1).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De facto, as drogas n\u00e3o ester\u00f3ide anti-inflamat\u00f3rias (NSAIDs) s\u00e3o eficazes na redu\u00e7\u00e3o da dor da artrite mas est\u00e3o tamb\u00e9m associadas a efeitos secund\u00e1rios muito conhecidos. A maioria dos que sofre com esses efeitos evita opi\u00f3ides e injec\u00e7\u00f5es intra-articular. Existem muita subst\u00e2ncias inclu\u00eddas no grupo de suplementos de articula\u00e7\u00e3o que d\u00e3o muito bons resultados na diminui\u00e7\u00e3o da dor articular. Al\u00e9m disso, os <strong>principais suplementos de articula\u00e7\u00e3o como Glucosamina Condroitina s\u00e3o excepcionalmente seguros<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quais S\u00e3o os Diferentes Tipos de Suplementos de Articula\u00e7\u00e3o?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A lista de suplementos de articula\u00e7\u00e3o investigados em estudos cient\u00edficos \u00e9 bastante longa (2). Ao lado dos maiores representantes, glucosamina e condroitina, estas subst\u00e2ncias tamb\u00e9m representam formas de tratar a dor articular:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Extrato de Boswellia serrata<\/li><li>Extrato de curcuma longa<\/li><li><strong><a href=\"https:\/\/eu.intelligentlabs.org\/pt-pt\/produto\/fitosoma-curcumina-meriva-500-mg\/\">Curcumina<\/a><\/strong><\/li><li>Metilsulfonilmetano (MSM)<\/li><li>Hidrolisado de col\u00e1genio<\/li><li>Col\u00e1genio tipo II n\u00e3o desnaturado<\/li><li>Extrato de casca de maracuj\u00e1<\/li><li>L-carnitinaGlu<\/li><li>Inaponific\u00e1veis da soja em abacate (ASU)<\/li><li>Diacere\u00edna<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Todos os suplementos de articula\u00e7\u00e3o acima mencionados demonstraram atividade analgesia na osteoartrite (2). Diferentes estudos revelaram diferentes resultados para o mesmo componente. N\u00e3o obstante, existem muitos estudos apoiantes relacionados a suplementos de articula\u00e7\u00f5es que representam o facto de n\u00e3o poderem ser esquecidos. Estas subst\u00e2ncias fornecem ajuda a muitas pessoas que sofrem com dor cr\u00f3nica na articula\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ca.intelligentlabs.org\/wp-content\/uploads\/sites\/2\/2020\/03\/glucosamine-chondroitin-joint-supplement-02.jpg\" alt=\"Glucosamina condroitina \u00e9 maioritariamente seguro o que \u00e9 muito importante para quem corre ou exercita regularmente\" width=\"1200\" height=\"712\">Glucosamina Condroitina \u00e9 Seguro?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In\u00fameros estudos real\u00e7am as excelentes propriedades seguras de suplementos de articula\u00e7\u00e3o, incluindo glucosamina e condroitina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um dos artigos cient\u00edficos que avaliou os efeitos da combina\u00e7\u00e3o de glucosamina e condroitina no tratamento de osteoartrite revelou que estes suplementos s\u00e3o seguros e n\u00e3o produzem eventos adversos (15). As caracter\u00edsticas de seguran\u00e7a dos suplementos de articula\u00e7\u00e3o s\u00e3o comparados com os de placebo (16). Estas qualidades de seguran\u00e7a s\u00e3o particularmente importantes se tivermos em mente que outras drogas utilizadas para al\u00edvio sistem\u00e1tico de dor cr\u00f3nica da articula\u00e7\u00e3o s\u00e3o associados a severos efeitos secund\u00e1rios (exemplo, NSAIDs).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem Deve Tomar Glucosamina Condroitina?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os suplementos de articula\u00e7\u00e3o representam uma importante modalidade de tratamento no controlo da osteoartrite. Pessoas com maior risco de desenvolver osteoatrite deveriam tamb\u00e9m utiliz\u00e1-los como forma de preven\u00e7\u00e3o&nbsp;(17).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos j\u00e1 afetados pela osteoatrite, o suplemento de articula\u00e7\u00e3o de glucosamina deveria ser utilizado para atrasar o progresso da doen\u00e7a e melhorar sintomas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existem diversos fatores que podem causar degenera\u00e7\u00e3o da articula\u00e7\u00e3o, e o seu tratamento n\u00e3o \u00e9 simples. Diversas medidas, tal como a perda de peso em pessoas com obesidade afetadas pela osteoartrite, fornece excelente resultados. Exerc\u00edcios selecionados, terapia f\u00edsica, e analg\u00e9sicos convencionais t\u00eam todos o seu papel importante no controlo dos sintomas de osteoartrite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Refer\u00eancias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Wilson PB. Dietary supplementation is more prevalent among adults with arthritis in the United States population. Complement Ther Med. 2016;29:152-157.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Liu X, Machado GC, Eyles JP, et al. Dietary supplements for treating osteoarthritis: a systematic review and meta-analysis. Br J Sports Med. 2018;52(3):167-175.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Phitak T, Pothacharoen P, Kongtawelert P. Comparison of glucose derivatives effects on cartilage degradation. BMC Musculoskelet Disord. 2010;11:162<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Reginster JY, Deroisy R, Rovati LC, et al. Long-term effects of glucosamine sulphate on osteoarthritis progression: a randomised, placebo-controlled clinical trial. Lancet. 2001;357(9252):251-256.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Tomaszewski W. Chondroitin \u2013 application in the treatment of degenerative joint disease.&nbsp;Ortop Traumatol Rehabil.&nbsp;2016;18(6):621-628.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. Bishnoi M, Jain A, Hurkat P, Jain SK. Chondroitin sulphate: a focus on osteoarthritis. Glycoconj J. 2016;33(5):693-705.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7. Singh JA, Noorbaloochi S, MacDonald R, Maxwell LJ. Chondroitin for osteoarthritis. Cochrane Database Syst Rev. 2015;1:CD005614.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8. Zhu X, Sang L, Wu D, Rong J, Jiang L. Effectiveness and safety of glucosamine and chondroitin for the treatment of osteoarthritis: a meta-analysis of randomized controlled trials. J Orthop Surg Res. 2018;13:170.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9. Ogata T, Ideno Y, Akai M, Seichi A, Hagino H, Iwaya T, et al. Effects of glucosamine in patients with osteoarthritis of the knee: a systematic review and meta-analysis. Clin Rheumatol. 2018;37(9):2479-2487.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10. Knapik JJ, Pope R, Hoedebecke SS, Schram B, Orr R, Lieberman HR. Effects of Oral Glucosamine Sulfate on Osteoarthritis-Related Pain and Joint-Space Changes: Systematic Review and Meta-Analysis. J Spec Oper Med. 2018;18(4):139-147.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11. Knapik JJ, Pope R, Hoedebecke SS, Schram B, Orr R. Effects of Oral Chondroitin Sulfate on Osteoarthritis-Related Pain and Joint Structural Changes: Systematic Review and Meta-Analysis. J Spec Oper Med. 2019;19(1):113-124.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12. Hsu CH, Hsu NC, Shih CL, Huang HT, Chen CH, Chou PH. Medication-Taking Habit and Outcome of Glucosamine Sulfate for Osteoarthritis Patients Influenced by National Health Insurance Regulations in Taiwan. J Clin Med. 2019; 8(10):pii: E1734.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13. Morita M, Yamada K, Date H, Hayakawa K, Sakurai H, Yamada H. Efficacy of Chondroitin Sulfate for Painful Knee Osteoarthritis: A One-Year, Randomized, Double-Blind, Multicenter Clinical Study in Japan. Biol. Pharm. Bull. 2018;1:163\u2013171.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14. Tsuji T, Yoon J, Kitano N, Okura T, Tanaka K. Effects of N-acetyl glucosamine and chondroitin sulfate supplementation on knee pain and self-reported knee function in middle-aged and older Japanese adults: a randomized, double-blind, placebo-controlled trial. Aging Clin. Exp. Res.,28, 197\u2013205 (2016)&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">15. Bottegoni C, Muzzarelli RA, Giovannini F, Busilacchi A, Gigante A. Oral chondroprotection with nutraceuticals made of chondroitin sulphate plus glucosamine sulphate in osteoarthritis. Carbohydr Polym. 2014;109:126-138.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16. Vangsness CT Jr, Spiker W, Erickson J. A review of evidence-based medicine for glucosamine and chondroitin sulfate use in knee osteoarthritis. Arthroscopy. 2009;25(1):86-94.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">17.&nbsp;<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Gallagher%20B%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24866892\" target=\"_blank\" rel=\"noreferrer noopener\">Gallagher B<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Tjoumakaris%20FP%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24866892\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Tjoumakaris FP<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Harwood%20MI%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24866892\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Harwood MI<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Good%20RP%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24866892\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Good RP<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Ciccotti%20MG%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24866892\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Ciccotti MG<\/a>,<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Freedman%20KB%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24866892\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Freedman KB<\/a>. Chondroprotection and the prevention of osteoarthritis progression of the knee: a systematic review of treatment agents. Am J Sports Med.2015;43(3):734-744.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Glucosamina condroitina \u00e9 um dos suplementos mais frequentemente utilizados para as articula\u00e7\u00f5es. Quimicamente, \u00e9 um amino-a\u00e7\u00facar. Este componente tem um papel importante na produ\u00e7\u00e3o e manuten\u00e7\u00e3o da cartilagem. Quando utilizado como um suplemento, o modo preciso da sua ac\u00e7\u00e3o analgesia e salva-guarda da cartilagem ao n\u00edvel molecular n\u00e3o \u00e9 totalmente conhecido. Provavelmente trabalha para&#8230;<\/p>\n","protected":false},"author":2,"featured_media":167994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[2099],"tags":[2236],"coauthors":[],"class_list":["post-168004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nutricao","tag-glucosamina"],"taxonomy_info":{"category":[{"value":2099,"label":"Nutri\u00e7\u00e3o"}],"post_tag":[{"value":2236,"label":"Glucosamina"}]},"featured_image_src_large":["https:\/\/eu.intelligentlabs.org\/wp-content\/uploads\/2025\/07\/glucosamina-condroitina-suplemento-para-articulacoes-01.jpg",1024,536,false],"author_info":{"display_name":"David Pashley","author_link":"https:\/\/eu.intelligentlabs.org\/pt-pt\/author\/david\/"},"comment_info":0,"category_info":[{"term_id":2099,"name":"Nutri\u00e7\u00e3o","slug":"nutricao","term_group":0,"term_taxonomy_id":2099,"taxonomy":"category","description":"","parent":0,"count":80,"filter":"raw","cat_ID":2099,"category_count":80,"category_description":"","cat_name":"Nutri\u00e7\u00e3o","category_nicename":"nutricao","category_parent":0}],"tag_info":[{"term_id":2236,"name":"Glucosamina","slug":"glucosamina","term_group":0,"term_taxonomy_id":2236,"taxonomy":"post_tag","description":"","parent":0,"count":6,"filter":"raw"}],"wpml":{"language":"pt-pt","is_original":false,"original_post_id":130266,"translations":{"cs-cz":{"id":218954,"language":"cs-cz","is_original":false},"da-dk":{"id":222329,"language":"da-dk","is_original":false},"de-at":{"id":208062,"language":"de-at","is_original":false},"de-de":{"id":38595,"language":"de-de","is_original":false},"el-cy":{"id":229566,"language":"el-cy","is_original":false},"el-gr":{"id":228143,"language":"el-gr","is_original":false},"en-gb":{"id":130266,"language":"en-gb","is_original":true},"en-ie":{"id":163748,"language":"en-ie","is_original":false},"es-es":{"id":44623,"language":"es-es","is_original":false},"fr-fr":{"id":29584,"language":"fr-fr","is_original":false},"hu-hu":{"id":225129,"language":"hu-hu","is_original":false},"it-it":{"id":45380,"language":"it-it","is_original":false},"nl-be":{"id":217857,"language":"nl-be","is_original":false},"nl-nl":{"id":182061,"language":"nl-nl","is_original":false},"pl-pl":{"id":196108,"language":"pl-pl","is_original":false},"pt-pt":{"id":168004,"language":"pt-pt","is_original":false},"sv-se":{"id":223255,"language":"sv-se","is_original":false}}},"_links":{"self":[{"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/posts\/168004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=168004"}],"version-history":[{"count":1,"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/posts\/168004\/revisions"}],"predecessor-version":[{"id":215876,"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/posts\/168004\/revisions\/215876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/media\/167994"}],"wp:attachment":[{"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=168004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=168004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=168004"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eu.intelligentlabs.org\/pt-pt\/wp-json\/wp\/v2\/coauthors?post=168004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}