{"id":2843,"count":1,"description":"","link":"https:\/\/eu.intelligentlabs.org\/el-cy\/product-category\/%ce%b1%ce%bd%cf%84%ce%b9%cf%86%ce%bb%ce%b5%ce%b3%ce%bc%ce%bf%ce%bd%cf%8e%ce%b4%ce%b5%cf%82\/","name":"\u0391\u03bd\u03c4\u03b9\u03c6\u03bb\u03b5\u03b3\u03bc\u03bf\u03bd\u03ce\u03b4\u03b5\u03c2","slug":"%ce%b1%ce%bd%cf%84%ce%b9%cf%86%ce%bb%ce%b5%ce%b3%ce%bc%ce%bf%ce%bd%cf%8e%ce%b4%ce%b5%cf%82","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"thumbnail_id":0,"wpml":{"language":"el-cy","is_original":false,"original_term_id":962,"translations":{"en-gb":{"id":962,"taxonomy":"product_cat","language":"en-gb","is_original":true},"fr-fr":{"id":967,"taxonomy":"product_cat","language":"fr-fr","is_original":false},"de-de":{"id":968,"taxonomy":"product_cat","language":"de-de","is_original":false},"it-it":{"id":969,"taxonomy":"product_cat","language":"it-it","is_original":false},"es-es":{"id":970,"taxonomy":"product_cat","language":"es-es","is_original":false},"en-ie":{"id":1992,"taxonomy":"product_cat","language":"en-ie","is_original":false},"en-mt":{"id":2091,"taxonomy":"product_cat","language":"en-mt","is_original":false},"de-at":{"id":2168,"taxonomy":"product_cat","language":"de-at","is_original":false},"pt-pt":{"id":2184,"taxonomy":"product_cat","language":"pt-pt","is_original":false},"nl-nl":{"id":2458,"taxonomy":"product_cat","language":"nl-nl","is_original":false},"nl-be":{"id":2490,"taxonomy":"product_cat","language":"nl-be","is_original":false},"fr-lu":{"id":2519,"taxonomy":"product_cat","language":"fr-lu","is_original":false},"cs-cz":{"id":2531,"taxonomy":"product_cat","language":"cs-cz","is_original":false},"da-dk":{"id":2558,"taxonomy":"product_cat","language":"da-dk","is_original":false},"sv-se":{"id":2601,"taxonomy":"product_cat","language":"sv-se","is_original":false},"hu-hu":{"id":2684,"taxonomy":"product_cat","language":"hu-hu","is_original":false},"bg-bg":{"id":2726,"taxonomy":"product_cat","language":"bg-bg","is_original":false},"el-gr":{"id":2796,"taxonomy":"product_cat","language":"el-gr","is_original":false},"el-cy":{"id":2843,"taxonomy":"product_cat","language":"el-cy","is_original":false},"et-ee":{"id":2888,"taxonomy":"product_cat","language":"et-ee","is_original":false},"lv-lv":{"id":2954,"taxonomy":"product_cat","language":"lv-lv","is_original":false},"lt-lt":{"id":3066,"taxonomy":"product_cat","language":"lt-lt","is_original":false},"ro-ro":{"id":3094,"taxonomy":"product_cat","language":"ro-ro","is_original":false},"fi-fi":{"id":3123,"taxonomy":"product_cat","language":"fi-fi","is_original":false},"sl-si":{"id":3226,"taxonomy":"product_cat","language":"sl-si","is_original":false},"sk-sk":{"id":3249,"taxonomy":"product_cat","language":"sk-sk","is_original":false}}},"_links":{"self":[{"href":"https:\/\/eu.intelligentlabs.org\/el-cy\/wp-json\/wp\/v2\/product_cat\/2843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.intelligentlabs.org\/el-cy\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/eu.intelligentlabs.org\/el-cy\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/eu.intelligentlabs.org\/el-cy\/wp-json\/wp\/v2\/product?product_cat=2843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}