{"id":1400,"count":1,"description":"","link":"https:\/\/eu.intelligentlabs.org\/de-de\/tag-de-de\/linderung-trockene-augen\/","name":"Linderung trockene Augen","slug":"linderung-trockene-augen","taxonomy":"post_tag","meta":[],"wpml":{"language":"de-de","is_original":true,"original_term_id":1400,"translations":{"de-de":{"id":1400,"taxonomy":"post_tag","language":"de-de","is_original":true}}},"_links":{"self":[{"href":"https:\/\/eu.intelligentlabs.org\/de-de\/wp-json\/wp\/v2\/tags\/1400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.intelligentlabs.org\/de-de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eu.intelligentlabs.org\/de-de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eu.intelligentlabs.org\/de-de\/wp-json\/wp\/v2\/posts?tags=1400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}